{"id":707,"date":"2020-07-01T17:37:58","date_gmt":"2020-07-01T17:37:58","guid":{"rendered":"https:\/\/fleetoptics.wpengine.com\/?p=707"},"modified":"2023-07-24T09:24:56","modified_gmt":"2023-07-24T13:24:56","slug":"covid-19-reshaping-last-mile-delivery-requirements","status":"publish","type":"post","link":"https:\/\/fleetopticsinc.com\/fr\/covid-19-reshaping-last-mile-delivery-requirements\/","title":{"rendered":"La COVID-19 red\u00e9finit les exigences de livraison du dernier kilom\u00e8tre"},"content":{"rendered":"<p>Les prestataires de services de livraison du dernier kilom\u00e8tre devront s'adapter aux changements durables dans la fa\u00e7on dont les magasins sont utilis\u00e9s, d\u00e9coulant de la pand\u00e9mie de la COVID-19. Brody Buhler, directeur g\u00e9n\u00e9ral mondial des services postaux et de colis chez Accenture, a averti lors d'une s\u00e9ance de Movin' On le 3 juin que la transformation des magasins physiques en centres de traitement des commandes n\u00e9cessitera des syst\u00e8mes de livraison efficaces.<\/p>\n<p>Les d\u00e9taillants ont d\u00e9j\u00e0 investi pour offrir des options telles que le clic et collecte (ramassage en bordure de trottoir) et la livraison locale, et souhaiteront maintenir ces options \u00e0 l'avenir, a d\u00e9clar\u00e9 Buhler.<\/p>\n<p>\u00ab Les investissements ont d\u00e9j\u00e0 \u00e9t\u00e9 r\u00e9alis\u00e9s \u00bb, a-t-il d\u00e9clar\u00e9. \u00ab Cette transformation de l'utilisation des magasins comme centres de traitement des commandes se poursuivra \u00e0 l'avenir et sera une nouvelle caract\u00e9ristique dominante de la nouvelle normalit\u00e9. \u00bb<\/p>\n<p>La COVID-19 a \u00e9galement acc\u00e9l\u00e9r\u00e9 l'utilisation du commerce \u00e9lectronique, une autre tendance qui, selon Buhler, est l\u00e0 pour rester. Une commande sur six est d\u00e9sormais effectu\u00e9e en ligne, contre une sur vingt avant la pand\u00e9mie, et un tout nouveau groupe de consommateurs traditionnels s'est converti par n\u00e9cessit\u00e9. Selon Buhler, il est peu probable qu'ils reviennent en arri\u00e8re une fois que les options de vente au d\u00e9tail traditionnelles reviendront.<\/p>\n<p>Le commerce \u00e9lectronique est \u00e9galement stimul\u00e9 par les r\u00e9percussions \u00e9conomiques de la COVID-19. Alors que plus de 33 millions d'Am\u00e9ricains sont nouvellement au ch\u00f4mage et qu'en France, 50 % des r\u00e9sidents b\u00e9n\u00e9ficient actuellement du soutien de l'\u00c9tat, il reste de l'argent \u00e0 d\u00e9penser en ligne. En effet, des options telles que les voyages, les divertissements et les sorties au restaurant ont disparu, laissant plus d'argent \u00e0 d\u00e9penser en ligne.<\/p>\n<p>Alors que les consommateurs restent plus pr\u00e8s de chez eux, le commerce local devient de plus en plus important.<\/p>\n<h5>\u00ab Les entreprises qui travaillent \u00e0 faciliter le commerce local seront probablement les grands gagnants \u00e0 l'avenir \u00bb, pr\u00e9dit Buhler.<\/h5>\n<h5>L'\u00e9tude de r\u00e9gions du monde o\u00f9 la pand\u00e9mie de COVID-19 s'est stabilis\u00e9e a r\u00e9v\u00e9l\u00e9 que les habitudes d'achat adopt\u00e9es pendant le confinement sont rest\u00e9es bien apr\u00e8s la stabilisation de la situation. \u00ab Les consommateurs vont progressivement retrouver leurs comportements normaux \u00bb, a d\u00e9clar\u00e9 Buhler. \u00ab Les consommateurs que vous pensiez conna\u00eetre, vous ne les connaissez plus. Tout a chang\u00e9. \u00bb<\/h5>\n<p>Les entreprises de livraison du dernier kilom\u00e8tre constatent un changement dans les volumes : moins de courrier, plus de colis, moins de B2B (entreprise \u00e0 entreprise), plus de B2C (entreprise \u00e0 consommateur). Les mod\u00e8les de livraison traditionnels, qui consistent \u00e0 exp\u00e9dier depuis un centre de distribution vers un d\u00e9p\u00f4t de livraison, puis vers le client, ne fonctionneront plus, a d\u00e9clar\u00e9 Buhler, car l'exp\u00e9dition se fera souvent du magasin au consommateur dans un rayon de cinq kilom\u00e8tres.<\/p>\n<p>Il faudra des syst\u00e8mes d'automatisation et de tri plus flexibles et \u00e9volutifs, qui pourront \u00eatre rapidement install\u00e9s dans des espaces existants. L'analyse des donn\u00e9es devra \u00eatre mieux utilis\u00e9e pour augmenter la capacit\u00e9 de traitement et l'efficacit\u00e9.<\/p>\n<p>Ces changements d'habitudes ont \u00e9galement des implications environnementales, avec plus de v\u00e9hicules de livraison ajout\u00e9s sur les routes, notamment dans les centres urbains. On estime qu'il y aura 36 % de v\u00e9hicules de livraison en plus sur les routes mondiales d'ici 2025, tandis que dans le m\u00eame temps, les grandes villes interdisent les v\u00e9hicules fonctionnant aux combustibles fossiles.<\/p>\n<p>Charles Brewer, directeur des op\u00e9rations de Postes Canada, a d\u00e9clar\u00e9 que son entreprise explore de nouvelles m\u00e9thodes de livraison, telles que les v\u00e9los cargos, dans les grandes villes. Il a \u00e9galement soulign\u00e9 que la COVID-19 a contraint la soci\u00e9t\u00e9 \u00e0 acc\u00e9l\u00e9rer ses investissements dans les capacit\u00e9s de commerce \u00e9lectronique.<\/p>\n<h5>\u00ab Les implications pour Postes Canada sont que tous ces projets que nous avions pr\u00e9vus pour les cinq \u00e0 dix prochaines ann\u00e9es en mati\u00e8re de robotique et d'automatisation doivent maintenant \u00eatre r\u00e9alis\u00e9s d'ici lundi \u00bb, a d\u00e9clar\u00e9 Brewer. \u00ab Notre univers a chang\u00e9 de mani\u00e8re incroyable. \u00bb<\/h5>\n<p>Bien qu'ils soient confront\u00e9s \u00e0 des d\u00e9fis pour s'adapter rapidement aux habitudes de vente au d\u00e9tail changeantes r\u00e9sultant de la pand\u00e9mie de COVID-19, les prestataires de services de livraison du dernier kilom\u00e8tre n'ont jamais \u00e9t\u00e9 autant appr\u00e9ci\u00e9s, a soulign\u00e9 Brewer.<\/p>\n<p>\u00ab Le niveau de reconnaissance pour ce que nos employ\u00e9s ont travers\u00e9 a \u00e9t\u00e9 absolument \u00e9crasant \u00bb, a d\u00e9clar\u00e9 Brewer. \u00ab La livraison n'a jamais \u00e9t\u00e9 aussi importante. \u00bb<\/p>\n<p>Added Buhler, \u201cYou have become the lifeline.\u201d<\/p>\n<p><strong>Source:<\/strong>\u00a0Source : Truck News. \"Covid-19 reshaping last mile delivery requirements\"<a href=\"https:\/\/www.trucknews.com\/business-management\/covid-19-reshaping-last-mile-delivery-requirements\/1003141283\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.trucknews.com\/business-management\/covid-19-reshaping-last-mile-delivery-requirements\/1003141283\/<\/a>). James Menzies. June 3, 2020.<\/p>","protected":false},"excerpt":{"rendered":"<p>Final mile delivery providers will need to adjust to lasting changes to how stores are used, stemming from the Covid-19 pandemic.Brody Buhler, global managing director, post and parcel with Accenture, warned during a Movin\u2019 On session June 3 that as brick-and-mortar stores are converted to fulfillment centers, efficient delivery systems will be paramount. Retailers have [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-insight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Covid-19 Reshaping Last Mile Delivery Requirements - FleetOptics Inc.<\/title>\n<meta name=\"description\" content=\"Final mile delivery providers will need to adjust to lasting changes to how stores are used, stemming from the Covid-19 pandemic.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fleetopticsinc.com\/fr\/covid-19-reshaping-last-mile-delivery-requirements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Covid-19 Reshaping Last Mile Delivery Requirements - FleetOptics Inc.\" \/>\n<meta property=\"og:description\" content=\"Final mile delivery providers will need to adjust to lasting changes to how stores are used, stemming from the Covid-19 pandemic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fleetopticsinc.com\/fr\/covid-19-reshaping-last-mile-delivery-requirements\/\" \/>\n<meta property=\"og:site_name\" content=\"FleetOptics Inc.\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-01T17:37:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T13:24:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fleetopticsinc.com\/wp-content\/uploads\/2023\/02\/Covid_BlogPost.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"The FleetOptics Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FleetOptics\" \/>\n<meta name=\"twitter:site\" content=\"@FleetOptics\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"The FleetOptics Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/\"},\"author\":{\"name\":\"The FleetOptics Team\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#\\\/schema\\\/person\\\/75bff3ebcdf2356124c1d745c48dce88\"},\"headline\":\"Covid-19 Reshaping Last Mile Delivery Requirements\",\"datePublished\":\"2020-07-01T17:37:58+00:00\",\"dateModified\":\"2023-07-24T13:24:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/\"},\"wordCount\":601,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fleetopticsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Covid_BlogPost.jpg\",\"articleSection\":[\"Industry Insight\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/\",\"url\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/\",\"name\":\"Covid-19 Reshaping Last Mile Delivery Requirements - FleetOptics Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fleetopticsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Covid_BlogPost.jpg\",\"datePublished\":\"2020-07-01T17:37:58+00:00\",\"dateModified\":\"2023-07-24T13:24:56+00:00\",\"description\":\"Final mile delivery providers will need to adjust to lasting changes to how stores are used, stemming from the Covid-19 pandemic.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fleetopticsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Covid_BlogPost.jpg\",\"contentUrl\":\"https:\\\/\\\/fleetopticsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Covid_BlogPost.jpg\",\"width\":1140,\"height\":640,\"caption\":\"Last Mile Delivery\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/covid-19-reshaping-last-mile-delivery-requirements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fleetopticsinc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Covid-19 Reshaping Last Mile Delivery Requirements\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#website\",\"url\":\"https:\\\/\\\/fleetopticsinc.com\\\/\",\"name\":\"FleetOptics Inc.\",\"description\":\"INNOVATING FINAL MILE DELIVERY\",\"publisher\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fleetopticsinc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#organization\",\"name\":\"FleetOptics Inc.\",\"url\":\"https:\\\/\\\/fleetopticsinc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fleetopticsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/FO_Logo_White-Footer.png\",\"contentUrl\":\"https:\\\/\\\/fleetopticsinc.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/FO_Logo_White-Footer.png\",\"width\":262,\"height\":52,\"caption\":\"FleetOptics Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/FleetOptics\",\"https:\\\/\\\/www.instagram.com\\\/fleetopticsinc\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCFV2m2sobBIQBu06dCbWnBw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fleetoptics-inc\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fleetopticsinc.com\\\/#\\\/schema\\\/person\\\/75bff3ebcdf2356124c1d745c48dce88\",\"name\":\"The FleetOptics Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98b0c85497e6a9199905d5efaf2b7081b1d38be2fc1a3891278de14fcaec72b4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98b0c85497e6a9199905d5efaf2b7081b1d38be2fc1a3891278de14fcaec72b4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98b0c85497e6a9199905d5efaf2b7081b1d38be2fc1a3891278de14fcaec72b4?s=96&d=mm&r=g\",\"caption\":\"The FleetOptics Team\"},\"url\":\"https:\\\/\\\/fleetopticsinc.com\\\/fr\\\/author\\\/the-fleet-optics-team\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covid-19 Reshaping Last Mile Delivery Requirements - FleetOptics Inc.","description":"Final mile delivery providers will need to adjust to lasting changes to how stores are used, stemming from the Covid-19 pandemic.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fleetopticsinc.com\/fr\/covid-19-reshaping-last-mile-delivery-requirements\/","og_locale":"fr_FR","og_type":"article","og_title":"Covid-19 Reshaping Last Mile Delivery Requirements - FleetOptics Inc.","og_description":"Final mile delivery providers will need to adjust to lasting changes to how stores are used, stemming from the Covid-19 pandemic.","og_url":"https:\/\/fleetopticsinc.com\/fr\/covid-19-reshaping-last-mile-delivery-requirements\/","og_site_name":"FleetOptics Inc.","article_published_time":"2020-07-01T17:37:58+00:00","article_modified_time":"2023-07-24T13:24:56+00:00","og_image":[{"width":1140,"height":640,"url":"https:\/\/fleetopticsinc.com\/wp-content\/uploads\/2023\/02\/Covid_BlogPost.jpg","type":"image\/jpeg"}],"author":"The FleetOptics Team","twitter_card":"summary_large_image","twitter_creator":"@FleetOptics","twitter_site":"@FleetOptics","twitter_misc":{"\u00c9crit par":"The FleetOptics Team","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/#article","isPartOf":{"@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/"},"author":{"name":"The FleetOptics Team","@id":"https:\/\/fleetopticsinc.com\/#\/schema\/person\/75bff3ebcdf2356124c1d745c48dce88"},"headline":"Covid-19 Reshaping Last Mile Delivery Requirements","datePublished":"2020-07-01T17:37:58+00:00","dateModified":"2023-07-24T13:24:56+00:00","mainEntityOfPage":{"@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/"},"wordCount":601,"commentCount":0,"publisher":{"@id":"https:\/\/fleetopticsinc.com\/#organization"},"image":{"@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/#primaryimage"},"thumbnailUrl":"https:\/\/fleetopticsinc.com\/wp-content\/uploads\/2023\/02\/Covid_BlogPost.jpg","articleSection":["Industry Insight"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/","url":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/","name":"Covid-19 Reshaping Last Mile Delivery Requirements - FleetOptics Inc.","isPartOf":{"@id":"https:\/\/fleetopticsinc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/#primaryimage"},"image":{"@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/#primaryimage"},"thumbnailUrl":"https:\/\/fleetopticsinc.com\/wp-content\/uploads\/2023\/02\/Covid_BlogPost.jpg","datePublished":"2020-07-01T17:37:58+00:00","dateModified":"2023-07-24T13:24:56+00:00","description":"Final mile delivery providers will need to adjust to lasting changes to how stores are used, stemming from the Covid-19 pandemic.","breadcrumb":{"@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/#primaryimage","url":"https:\/\/fleetopticsinc.com\/wp-content\/uploads\/2023\/02\/Covid_BlogPost.jpg","contentUrl":"https:\/\/fleetopticsinc.com\/wp-content\/uploads\/2023\/02\/Covid_BlogPost.jpg","width":1140,"height":640,"caption":"Last Mile Delivery"},{"@type":"BreadcrumbList","@id":"https:\/\/fleetopticsinc.com\/covid-19-reshaping-last-mile-delivery-requirements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fleetopticsinc.com\/"},{"@type":"ListItem","position":2,"name":"Covid-19 Reshaping Last Mile Delivery Requirements"}]},{"@type":"WebSite","@id":"https:\/\/fleetopticsinc.com\/#website","url":"https:\/\/fleetopticsinc.com\/","name":"FleetOptics","description":"INNOVATING FINAL MILE DELIVERY","publisher":{"@id":"https:\/\/fleetopticsinc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fleetopticsinc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fleetopticsinc.com\/#organization","name":"FleetOptics","url":"https:\/\/fleetopticsinc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fleetopticsinc.com\/#\/schema\/logo\/image\/","url":"https:\/\/fleetopticsinc.com\/wp-content\/uploads\/2023\/02\/FO_Logo_White-Footer.png","contentUrl":"https:\/\/fleetopticsinc.com\/wp-content\/uploads\/2023\/02\/FO_Logo_White-Footer.png","width":262,"height":52,"caption":"FleetOptics Inc."},"image":{"@id":"https:\/\/fleetopticsinc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/FleetOptics","https:\/\/www.instagram.com\/fleetopticsinc\/","https:\/\/www.youtube.com\/channel\/UCFV2m2sobBIQBu06dCbWnBw","https:\/\/www.linkedin.com\/company\/fleetoptics-inc\/"]},{"@type":"Person","@id":"https:\/\/fleetopticsinc.com\/#\/schema\/person\/75bff3ebcdf2356124c1d745c48dce88","name":"The FleetOptics Team","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/98b0c85497e6a9199905d5efaf2b7081b1d38be2fc1a3891278de14fcaec72b4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98b0c85497e6a9199905d5efaf2b7081b1d38be2fc1a3891278de14fcaec72b4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98b0c85497e6a9199905d5efaf2b7081b1d38be2fc1a3891278de14fcaec72b4?s=96&d=mm&r=g","caption":"The FleetOptics Team"},"url":"https:\/\/fleetopticsinc.com\/fr\/author\/the-fleet-optics-team\/"}]}},"_links":{"self":[{"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/posts\/707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/comments?post=707"}],"version-history":[{"count":0,"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/posts\/707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/media\/708"}],"wp:attachment":[{"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/media?parent=707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/categories?post=707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fleetopticsinc.com\/fr\/wp-json\/wp\/v2\/tags?post=707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}